{"id":785,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/zh\/tag\/conveyor-chain-canada-china\/","name":"Conveyor Chain Canada China","slug":"conveyor-chain-canada-china","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/zh\/wp-json\/wp\/v2\/tags\/785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/zh\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/zh\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/zh\/wp-json\/wp\/v2\/posts?tags=785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}