{"id":602,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/zh\/tag\/silent-chain-sprocket-china\/","name":"\u4e2d\u56fd\u9759\u97f3\u94fe\u8f6e","slug":"silent-chain-sprocket-china","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/zh\/wp-json\/wp\/v2\/tags\/602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/zh\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/zh\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/zh\/wp-json\/wp\/v2\/posts?tags=602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}