{"id":2465,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/zh\/tag\/\u4e09\u661f-gear-\u5145\u7535\u5e95\u5ea7\/","name":"\u4e09\u661f Gear \u5145\u7535\u5e95\u5ea7","slug":"samsung-gear-charging-dock","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/zh\/wp-json\/wp\/v2\/tags\/2465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/zh\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/zh\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/zh\/wp-json\/wp\/v2\/posts?tags=2465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}