{"id":792,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/vi\/tag\/sprocket-chain-wheel-china\/","name":"Sprocket Chain Wheel China","slug":"sprocket-chain-wheel-china","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/vi\/wp-json\/wp\/v2\/tags\/792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/vi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/vi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/vi\/wp-json\/wp\/v2\/posts?tags=792"}],"curies":[{"name":"trang web","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}