{"id":1436,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/vi\/tag\/hop-so-may-tron\/","name":"h\u1ed9p s\u1ed1 m\u00e1y tr\u1ed9n","slug":"mixer-gearbox","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/vi\/wp-json\/wp\/v2\/tags\/1436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/vi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/vi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/vi\/wp-json\/wp\/v2\/posts?tags=1436"}],"curies":[{"name":"trang web","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}