{"id":1367,"count":2,"description":"","link":"https:\/\/forgedbevelgear.com\/sv\/tag\/jordbrukstraktorns-vaxellada\/","name":"jordbrukstraktorns v\u00e4xell\u00e5da","slug":"agricultural-tractor-gearbox","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/sv\/wp-json\/wp\/v2\/tags\/1367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/sv\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/sv\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/sv\/wp-json\/wp\/v2\/posts?tags=1367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}