{"id":685,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/nl\/tag\/pin-conveyor\/","name":"pin conveyor","slug":"pin-conveyor","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/nl\/wp-json\/wp\/v2\/tags\/685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/nl\/wp-json\/wp\/v2\/posts?tags=685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}