{"id":219,"count":3,"description":"","link":"https:\/\/forgedbevelgear.com\/nl\/tag\/conveyor-roller-chain-sprocket\/","name":"Transportbandrolkettingtandwiel","slug":"conveyor-roller-chain-sprocket","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/nl\/wp-json\/wp\/v2\/tags\/219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/nl\/wp-json\/wp\/v2\/posts?tags=219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}