{"id":1092,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/nl\/tag\/pulley-conveyor\/","name":"pulley conveyor","slug":"pulley-conveyor","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/nl\/wp-json\/wp\/v2\/tags\/1092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/nl\/wp-json\/wp\/v2\/posts?tags=1092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}