{"id":689,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/nb\/tag\/rullekjedepinne\/","name":"rullekjedepinne","slug":"roller-chain-pin","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/nb\/wp-json\/wp\/v2\/tags\/689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/nb\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/nb\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/nb\/wp-json\/wp\/v2\/posts?tags=689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}