{"id":1625,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/nb\/tag\/turtallsgir\/","name":"turtallsgir","slug":"rpm-gear","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/nb\/wp-json\/wp\/v2\/tags\/1625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/nb\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/nb\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/nb\/wp-json\/wp\/v2\/posts?tags=1625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}