{"id":886,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/ms\/tag\/capacitor-motor-for\/","name":"capacitor motor for","slug":"capacitor-motor-for","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/ms\/wp-json\/wp\/v2\/tags\/886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/ms\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/ms\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/ms\/wp-json\/wp\/v2\/posts?tags=886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}