{"id":1366,"count":2,"description":"","link":"https:\/\/forgedbevelgear.com\/ms\/tag\/kotak-gear-pto-pertanian-2\/","name":"kotak gear pto pertanian","slug":"agricultural-pto-gearbox","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/ms\/wp-json\/wp\/v2\/tags\/1366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/ms\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/ms\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/ms\/wp-json\/wp\/v2\/posts?tags=1366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}