{"id":2487,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/ko\/tag\/\uc2a4\ud14c\uc778\ub9ac\uc2a4-\uc2a4\ud2f8-\uae30\uc5b4\ubc15\uc2a4\/","name":"\uc2a4\ud14c\uc778\ub9ac\uc2a4 \uc2a4\ud2f8 \uae30\uc5b4\ubc15\uc2a4","slug":"stainless-steel-gear-box","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/ko\/wp-json\/wp\/v2\/tags\/2487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/ko\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/ko\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/ko\/wp-json\/wp\/v2\/posts?tags=2487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}