{"id":1135,"count":2,"description":"","link":"https:\/\/forgedbevelgear.com\/ko\/tag\/\uc2a4\ud0c0\ud130-\uae30\uc5b4\/","name":"\uc2a4\ud0c0\ud130 \uae30\uc5b4","slug":"starter-gear","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/ko\/wp-json\/wp\/v2\/tags\/1135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/ko\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/ko\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/ko\/wp-json\/wp\/v2\/posts?tags=1135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}