{"id":1400,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/ja\/tag\/\u30ae\u30a2\u6e1b\u901f\u6a5f\u30df\u30cb\/","name":"\u30ae\u30a2\u6e1b\u901f\u6a5f\u30df\u30cb","slug":"gear-reducer-mini","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/ja\/wp-json\/wp\/v2\/tags\/1400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/ja\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/ja\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/ja\/wp-json\/wp\/v2\/posts?tags=1400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}