{"id":258,"count":4,"description":"","link":"https:\/\/forgedbevelgear.com\/it\/tag\/roller-chain-conveyor-parts\/","name":"Componenti per trasportatori a catena a rulli","slug":"roller-chain-conveyor-parts","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/it\/wp-json\/wp\/v2\/tags\/258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/it\/wp-json\/wp\/v2\/posts?tags=258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}