{"id":1698,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/it\/tag\/film-agricolo\/","name":"film agricolo","slug":"agriculture-film","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/it\/wp-json\/wp\/v2\/tags\/1698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/it\/wp-json\/wp\/v2\/posts?tags=1698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}