{"id":677,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/id\/tag\/conveyor-pin-chain\/","name":"conveyor pin chain","slug":"conveyor-pin-chain","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/id\/wp-json\/wp\/v2\/tags\/677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/id\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/id\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/id\/wp-json\/wp\/v2\/posts?tags=677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}