{"id":2328,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/id\/tag\/gearbox-planet-torsi-tinggi\/","name":"gearbox planet torsi tinggi","slug":"high-torque-planetary-gearbox","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/id\/wp-json\/wp\/v2\/tags\/2328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/id\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/id\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/id\/wp-json\/wp\/v2\/posts?tags=2328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}