{"id":2417,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/fr\/tag\/water-gear\/","name":"water gear","slug":"water-gear","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/fr\/wp-json\/wp\/v2\/tags\/2417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/fr\/wp-json\/wp\/v2\/posts?tags=2417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}