{"id":2193,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/fr\/tag\/accessoires-pour-pieces-de-moteur\/","name":"accessoires pour pi\u00e8ces de moteur","slug":"motor-parts-accessories","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/fr\/wp-json\/wp\/v2\/tags\/2193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/fr\/wp-json\/wp\/v2\/posts?tags=2193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}