{"id":785,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/fa\/tag\/\u0632\u0646\u062c\u06cc\u0631-\u0646\u0648\u0627\u0631-\u0646\u0642\u0627\u0644\u0647-\u06a9\u0627\u0646\u0627\u062f\u0627-\u0686\u06cc\u0646\/","name":"Conveyor Chain Canada China","slug":"conveyor-chain-canada-china","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/fa\/wp-json\/wp\/v2\/tags\/785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/fa\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/fa\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/fa\/wp-json\/wp\/v2\/posts?tags=785"}],"curies":[{"name":"\u0648\u0631\u062f\u067e\u0631\u0633","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}