{"id":375,"count":3,"description":"","link":"https:\/\/forgedbevelgear.com\/fa\/tag\/\u062a\u0648\u0644\u06cc\u062f-\u06a9\u0646\u0646\u062f\u0647-\u0686\u0631\u062e-\u062f\u0646\u062f\u0647\/","name":"\u062a\u0648\u0644\u06cc\u062f \u06a9\u0646\u0646\u062f\u0647 \u0686\u0631\u062e \u062f\u0646\u062f\u0647","slug":"manufacturer-of-sprocket","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/fa\/wp-json\/wp\/v2\/tags\/375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/fa\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/fa\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/fa\/wp-json\/wp\/v2\/posts?tags=375"}],"curies":[{"name":"\u0648\u0631\u062f\u067e\u0631\u0633","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}