{"id":691,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/es\/tag\/roller-chain-with-pin\/","name":"roller chain with pin","slug":"roller-chain-with-pin","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/es\/wp-json\/wp\/v2\/tags\/691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/es\/wp-json\/wp\/v2\/posts?tags=691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}