{"id":1484,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/es\/tag\/carcasa-del-engranaje-planetario\/","name":"carcasa del engranaje planetario","slug":"planetary-gear-housing","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/es\/wp-json\/wp\/v2\/tags\/1484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/es\/wp-json\/wp\/v2\/posts?tags=1484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}