{"id":1297,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/es\/tag\/pasador-del-eje\/","name":"pasador del eje","slug":"shaft-pin","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/es\/wp-json\/wp\/v2\/tags\/1297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/es\/wp-json\/wp\/v2\/posts?tags=1297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}