{"id":1995,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/en\/tag\/china-heavy-roller-chains\/","name":"china heavy roller chains","slug":"china-heavy-roller-chains","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/en\/wp-json\/wp\/v2\/tags\/1995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/en\/wp-json\/wp\/v2\/posts?tags=1995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}