{"id":393,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/de\/tag\/agricultural-conveyor-chain\/","name":"Landwirtschaftliche F\u00f6rderkette","slug":"agricultural-conveyor-chain","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/de\/wp-json\/wp\/v2\/tags\/393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/de\/wp-json\/wp\/v2\/posts?tags=393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}