{"id":1084,"count":1,"description":"","link":"https:\/\/forgedbevelgear.com\/de\/tag\/belt-conveyor-pulley\/","name":"belt conveyor pulley","slug":"belt-conveyor-pulley","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/forgedbevelgear.com\/de\/wp-json\/wp\/v2\/tags\/1084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgedbevelgear.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/forgedbevelgear.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/forgedbevelgear.com\/de\/wp-json\/wp\/v2\/posts?tags=1084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}